{"id":1908,"date":"2021-02-01T08:56:30","date_gmt":"2021-02-01T07:56:30","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/"},"modified":"2021-02-05T10:03:05","modified_gmt":"2021-02-05T09:03:05","slug":"leuropa-si-fa-in-treno","status":"publish","type":"post","link":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/","title":{"rendered":"L\u2019Europa si fa in treno"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom-300x200.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"Rene\u0301 Frampe\" loading=\"lazy\" style=\"display: block; margin-bottom: 5px; clear:both;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom-300x200.jpg 300w, https:\/\/www.lanuovaecologia.it\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom-150x100.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h6><strong>La defiscalizzazione dei biglietti in alcuni Paesi ne fa scendere i costi e favorisce l\u2019abbandono di auto e aereo. La Commissione dedica il 2021 alle ferrovie. In cerca di sostenibilit\u00e0, sicurezza e velocit\u00e0<\/strong><\/h6>\n<p>di ELENA COMELLI<\/p>\n<p><a href=\"https:\/\/www.lanuovaecologia.it\/gennaio-2021\/\"><strong>Dal mensile di gennaio<\/strong><\/a> &#8211; La rivoluzione verde dei trasporti corre sui binari. La rimonta del treno in questo periodo di emergenza sanitaria, con gli aerei a terra e il crollo del consumo di carburanti, \u00e8 una rivincita importante per gli spostamenti su rotaia, che dimostrano di essere il modo di viaggiare pi\u00f9 resiliente di fronte alle crisi.<\/p>\n<p>I trasporti di merci e persone sono responsabili di oltre un quinto (21%) delle emissioni globali di gas serra. Di queste, il 75% \u00e8 generato dai veicoli su gomma, l\u201911% ciascuno da navi e aerei, il 2% dai trasporti di materie prime via tubo e solo l\u20191% dalle ferrovie. Fin dalla sua nascita, e ancora di pi\u00f9 con la sua elettrificazione a fine Ottocento, il treno resta il mezzo di gran lunga pi\u00f9 efficiente. Muove ogni giorno l\u20198% delle persone nel mondo e il 7% delle merci, ma consuma solo il 2% dell\u2019energia richiesta dai trasporti. Questo \u00e8 il motivo per cui la Commissione europea, nel suo sforzo di promuovere lo sviluppo sostenibile, spinge molto sulle ferrovie e ha eletto il 2021 \u201cAnno europeo del treno\u201d, come parte della nuova Agenda verde. \u201cNon c\u2019\u00e8 alcun dubbio che il trasporto ferroviario, quando \u00e8 organizzato e progettato secondo i principi del XXI secolo, comporta enormi vantaggi nella maggior parte dei settori: sostenibilit\u00e0, sicurezza e persino velocit\u00e0\u201d, ha detto la commissaria per i Trasporti, Adina V\u0103lean, al lancio dell\u2019iniziativa, che coincider\u00e0 con l\u2019entrata in vigore in tutto il continente del quarto pacchetto ferroviario e con la completa liberalizzazione del settore.<\/p>\n<p><iframe title=\"Il treno dei desideri\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/OzuUEpLwSmY?start=2&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2><strong>Trasporto merci su rotaia, obiettivo 30%<\/strong><\/h2>\n<p>L\u2019obiettivo di Bruxelles al 2030 \u00e8 portare al 30% il trasporto merci su rotaia contro il 18% attuale e aumentare il pi\u00f9 possibile il numero di persone che scelgono il treno al posto della macchina o dell\u2019aereo, soprattutto nei viaggi transfrontalieri entro i mille chilometri, con facilitazioni tariffarie e una maggiore interoperabilit\u00e0 dei sistemi, ma anche eliminando i sussidi per il trasporto aereo e facendo pagare di pi\u00f9 i costi dell\u2019inquinamento a chi vuole viaggiare in autostrada. Attendiamoci, quindi, prezzi pi\u00f9 alti per i biglietti aerei e pi\u00f9 abbordabili per i viaggi in treno: la Germania, ad esempio, ha gi\u00e0 tagliato dal 19 al 7% l\u2019Iva sui viaggi in treno di oltre 50 chilometri, il che si \u00e8 tradotto in una riduzione del 10% dei prezzi dei biglietti. Con questi sconti, Deutsche Bahn prevede una crescita di 5 milioni di passeggeri all\u2019anno.<\/p>\n<p>La domanda europea di viaggi in treno aumenter\u00e0 fortemente nel prossimo decennio anche in base a uno studio della svizzera Ubs Research, che fa riferimento al nuovo apprezzamento dell\u2019opinione pubblica per l\u2019aria pi\u00f9 pulita, a seguito della pandemia di Covid-19, come a un momento di svolta per i mezzi di trasporto, con un aumento della tolleranza del pubblico verso viaggi pi\u00f9 lunghi ma pi\u00f9 puliti. Questo spostamento dei gusti del pubblico verso modi di viaggiare pi\u00f9 ecologici sar\u00e0 un vantaggio per il mercato europeo dell\u2019alta velocit\u00e0 ferroviaria, che secondo gli analisti del colosso bancario svizzero \u00e8 destinato a crescere del 10% all\u2019anno in questo decennio.<\/p>\n<blockquote>\n<p>Ammonta al 24% il contributo dei trasporti alle emissioni di C02: l&#8217;11,6% sono emissioni del trasporto aereo (81% passeggeri, 11,6% merci), il 10,6% del trasporto navale, il 2% provengono da altri trasporti (olio, gas e acqua), mentre solo l&#8217;1% dal trasporto ferroviario &#8211; <strong>OurWorldData.org su report International Energy Agency e International Council on Clean Transportation<\/strong><\/p>\n<\/blockquote>\n<h2><strong>Treni, nel mirino il sorpasso sull\u2019aereo<\/strong><\/h2>\n<p>Non a caso, negli ultimi mesi c\u2019\u00e8 stata una rinascita dei treni notturni in tutta Europa. Le ferrovie austriache \u00d6bb hanno riesumato il notturno fra Vienna e Bruxelles e un nuovo notturno della svedese Trafikverket coprir\u00e0 la tratta Malm\u00f6-Londra, passando per Copenhagen e Colonia. Fioriscono anche nuove tratte di alta velocit\u00e0, come quella di sei ore fra Parigi e Barcellona, con importanti ricadute negative per il traffico aereo. Lo studio Ubs evidenzia l\u2019impatto dell\u2019alta velocit\u00e0 sulle rotte Londra-Parigi, Madrid-Barcellona e Monaco-Berlino, che hanno ormai soppiantato in larga misura le linee aeree, grazie alla comodit\u00e0 di partire e di arrivare direttamente in centro citt\u00e0 e di evitare i tempi morti in aeroporto. L\u2019Eurostar, tanto per fare un esempio, ha pi\u00f9 che dimezzato i passeggeri sui voli Londra-Parigi e Londra-Bruxelles, mentre l\u2019alta velocit\u00e0 in Italia ha avuto ricadute analoghe lungo tutta la linea Torino-Napoli.<\/p>\n<p>La sfida da affrontare ora, oltre ad ampliare la quota di viaggi in ferrovia, sar\u00e0 l\u2019ulteriore decarbonizzazione dei treni, che comunque nell\u2019Ue hanno gi\u00e0 aumentato la loro efficienza energetica del 22% negli ultimi trent\u2019anni. Da un lato ci si muove verso l\u2019elettrificazione delle linee su cui circolano ancora i treni diesel, dall\u2019altro lato verso la sostituzione dei vecchi convogli con treni nuovi alimentati a idrogeno. In Italia, dove il 28% delle linee (4.760 chilometri) non \u00e8 elettrificato, si stanno facendo notevoli sforzi: il gruppo Fs prevede di elettrificare 670 chilometri di linee entro il 2024, per un investimento di oltre 1,4 miliardi di euro, e altri 1.670 nel quinquennio successivo, con 2,4 miliardi d\u2019investimento.<\/p>\n<h2><strong>Treni, il futuro sar\u00e0 a idrogeno<\/strong><\/h2>\n<p>L\u2019introduzione di locomotori a idrogeno al posto di quelli diesel \u00e8 una soluzione alternativa all\u2019elettrificazione, che evita di tirare linee aeree sui segmenti che mancano, ma pone il problema dell\u2019origine dell\u2019idrogeno utilizzato: il 97%, ad oggi, si produce da combustibili fossili, rilasciando oltre 800 milioni di tonnellate di CO2 l\u2019anno a livello globale, quanto le emissioni di un Paese come la Germania. Molto pi\u00f9 caro, ma totalmente pulito (emette ossigeno), \u00e8 invece l\u2019idrogeno \u201cverde\u201d, ricavato da fonti rinnovabili con l\u2019elettrolisi dell\u2019acqua. L\u2019idrogeno \u201cblu\u201d, prodotto con il reforming del metano e con la cattura e stoccaggio delle relative emissioni, \u00e8 un compromesso molto amato dalle compagnie petrolifere, da Shell a Bp, che per\u00f2 non \u00e8 ancora applicato a livello commerciale. In una prospettiva di crescente diffusione dell\u2019idrogeno verde, sulla spinta della roadmap europea di sviluppo per questo vettore pulito, l\u2019utilizzo di idrogeno al posto del diesel \u00e8 comunque un passo avanti sulla strada di un\u2019ulteriore decarbonizzazione delle ferrovie, perch\u00e9 non produce emissioni climalteranti al momento dell\u2019utilizzo (emette solo acqua). Ecco perch\u00e9 diversi operatori ferroviari si stanno rivolgendo in questa direzione. In Italia i primi treni a idrogeno, prodotti dalla francese Alstom nel suo stabilimento piemontese di Savigliano, entreranno in servizio nel 2023 sulla rete di Trenord, sulla linea Brescia-Iseo-Edolo che attraversa la Valcamonica. L\u2019obiettivo \u00e8 sostituire i 14 treni diesel che attualmente operano sulla linea e realizzare in loco un impianto di produzione di \u201cidrogeno blu\u201d in modo da avvicinare la produzione e l\u2019utilizzo, promuovendo cos\u00ec la prima Hydrogen valley italiana. Il progetto \u201cH2iseO\u201d \u00e8 stato avviato a novembre da Ferrovie Nord Milano con un investimento di 160 milioni per i primi sei treni e con lo studio di fattibilit\u00e0 per il primo impianto di produzione di idrogeno a Iseo, nell\u2019area del deposito di Trenord, da realizzare entro il 2023. L\u2019impianto user\u00e0 il metodo del reforming del metano, sperimentando anche la cattura e lo stoccaggio della CO2. Il progetto punta poi a realizzare entro il 2025 uno o due impianti di produzione di idrogeno verde da elettrolisi dell\u2019acqua lungo il tracciato della ferrovia e di estendere l\u2019utilizzo dell\u2019idrogeno al trasporto pubblico locale, ma questo \u00e8 tutto di l\u00e0 da venire.<\/p>\n<h2><strong>In Germania il primo locomotore a idrogeno del mondo<br \/>\n<\/strong><\/h2>\n<p>Il primo locomotore a idrogeno del mondo, sempre Alstom, \u00e8 entrato in servizio nel 2018 su una linea regionale in Bassa Sassonia, che l\u2019operatore locale considerava troppo costosa da elettrificare. L\u2019azienda ferroviaria regionale ha riportato buoni risultati nei primi due anni di attivit\u00e0, spingendo la diffusione di questo modello in Austria e in Olanda. Anche la Deutsche Bahn ha annunciato il mese scorso l\u2019intenzione di sviluppare insieme a Siemens un proprio locomotore a idrogeno. Il \u201cMireo plus H\u201d avr\u00e0 un\u2019autonomia di 600 chilometri e una velocit\u00e0 massima di 150 chilometri all\u2019ora: le prove sul nuovo treno inizieranno nel 2024 nel Baden-W\u00fcrttemberg, con l\u2019idea di alimentarlo a idrogeno verde, prodotto da energia eolica. Deutsche Bahn ha in esercizio oltre 1.300 locomotori diesel sulle linee regionali: il 39% della rete ferroviaria tedesca non \u00e8 elettrificata e il governo si era impegnato a raggiungere il 70% entro il 2025, ma i progressi sono lenti. Di conseguenza Deutsche Bahn dovr\u00e0 rivolgersi sempre di pi\u00f9 all\u2019idrogeno verde per raggiungere i suoi ambiziosi obiettivi di neutralit\u00e0 climatica, una mossa che potrebbe trainare anche le altre ferrovie europee sulla stessa strada.<\/p>\n<blockquote>\n<p><strong>Per approfondire<br \/>\n<\/strong><a href=\"https:\/\/www.lanuovaecologia.it\/trasporto-locale-italia-risorse\/\">Trasporto locale, ritardo in bozza<\/a><br \/>\n<a href=\"https:\/\/www.lanuovaecologia.it\/tav-torino-lione-legambiente-proteste\/\">Tav Torino-Lione, Legambiente: &#8220;Non \u00e8 un progetto di linea ferroviaria&#8221;<\/a><br \/>\n<a href=\"https:\/\/www.lanuovaecologia.it\/treni-libri-film\/\">Arte in carozza: libri, poesie e film sul mondo dei treni<\/a><\/p>\n<\/blockquote>\n<h3><strong><a href=\"https:\/\/a2f3e0.emailsp.com\/frontend\/forms\/Subscription.aspx?idList=3&amp;idForm=6&amp;guid=3a0cb849-9df7-455a-8512-dc7199ae3fd8\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La defiscalizzazione dei biglietti in alcuni Paesi ne fa scendere i costi e favorisce l\u2019abbandono di auto e aereo. La Commissione dedica il 2021 alle ferrovie. In cerca di sostenibilit\u00e0, sicurezza e velocit\u00e0 di ELENA COMELLI Dal mensile di gennaio &#8211; La rivoluzione verde dei trasporti corre sui binari. La rimonta del treno in questo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019Europa si fa in treno - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Europa si fa in treno - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"La defiscalizzazione dei biglietti in alcuni Paesi ne fa scendere i costi e favorisce l\u2019abbandono di auto e aereo. La Commissione dedica il 2021 alle ferrovie. In cerca di sostenibilit\u00e0, sicurezza e velocit\u00e0 di ELENA COMELLI Dal mensile di gennaio &#8211; La rivoluzione verde dei trasporti corre sui binari. La rimonta del treno in questo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T07:56:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-05T09:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"L\u2019Europa si fa in treno\",\"datePublished\":\"2021-02-01T07:56:30+00:00\",\"dateModified\":\"2021-02-05T09:03:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/\"},\"wordCount\":1450,\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/\",\"url\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/\",\"name\":\"L\u2019Europa si fa in treno - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg\",\"datePublished\":\"2021-02-01T07:56:30+00:00\",\"dateModified\":\"2021-02-05T09:03:05+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg\",\"width\":630,\"height\":420},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\/\/forumqualenergia.it\"],\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Europa si fa in treno - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019Europa si fa in treno - ForumQualEnergia 2023","og_description":"La defiscalizzazione dei biglietti in alcuni Paesi ne fa scendere i costi e favorisce l\u2019abbandono di auto e aereo. La Commissione dedica il 2021 alle ferrovie. In cerca di sostenibilit\u00e0, sicurezza e velocit\u00e0 di ELENA COMELLI Dal mensile di gennaio &#8211; La rivoluzione verde dei trasporti corre sui binari. La rimonta del treno in questo [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2021-02-01T07:56:30+00:00","article_modified_time":"2021-02-05T09:03:05+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/"},"author":{"name":"ecfrm","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"L\u2019Europa si fa in treno","datePublished":"2021-02-01T07:56:30+00:00","dateModified":"2021-02-05T09:03:05+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/"},"wordCount":1450,"publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/leuropa-si-fa-in-treno\/","url":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/","name":"L\u2019Europa si fa in treno - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg","datePublished":"2021-02-01T07:56:30+00:00","dateModified":"2021-02-05T09:03:05+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/treni-idrogeno-europa\/#primaryimage","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/Coradia-iLint1_\u00a9-Rene\u0301-Frampe-alstom.jpg","width":630,"height":420},{"@type":"WebSite","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website","url":"https:\/\/staging.forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/staging.forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=1908"}],"version-history":[{"count":0,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/1909"}],"wp:attachment":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=1908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=1908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=1908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}