{"id":3599,"date":"2022-03-31T10:00:57","date_gmt":"2022-03-31T08:00:57","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/"},"modified":"2022-04-07T13:03:04","modified_gmt":"2022-04-07T11:03:04","slug":"gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione","status":"publish","type":"post","link":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/","title":{"rendered":"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"348\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin: auto; margin-bottom: 5px;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg 620w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg 150w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<h6><strong>Riqualificando ogni anno il 3% del patrimonio edilizio e puntando sulle pompe di calore, al 2030 si potrebbe arrivare a 12 miliardi di metro cubi in meno, pari al 41% delle importazioni da Mosca. Le proposte di Legambiente e Kyoto Club nel nuovo studio di Elemens \u201cDal Gas alle rinnovabili&#8221;<\/strong><\/h6>\n<p><span id=\"more-253828\"><\/span><\/p>\n<p>Ci sono strade concrete da percorrere per ridurre i consumi di gas, la dipendenza dalle forniture della Russia e, in parallelo, abbattere sensibilmente le emissioni climalteranti migliorando la qualit\u00e0 dell\u2019aria e alleggerire il costo della bolletta. Secondo Legambiente e Kyoto Club lo si pu\u00f2 fare partendo dall&#8217;efficientamento del parco edilizio e dall&#8217;elettrificazione dei consumi per il riscaldamento domestico.<\/p>\n<p>Per le associazioni se l&#8217;Italia percorresse contemporaneamente queste due strade, riqualificando ogni anno il 3% del patrimonio edilizio, come prevede la nuova strategia europea <em>Renovation Wave<\/em>, portandolo da una performance media di consumo di energia finale termica di 136 kWh\/m2\/anno (media attuale tra residenziale e civile) a circa 50 kWh\/m2\/anno ed elettrificando i consumi per il riscaldamento domestico puntando sulle pompe di calore, i risultati sarebbero evidenti, da subito. I consumi di gas si potrebbero ridurre da qui al 2025 di oltre 5,4 miliardi di metri cubi all\u2019anno per arrivare al 2030 a ben 12 miliardi di metro cubi, pari al 41% delle importazioni dalla Russia. In contemporanea ci sarebbe un risparmio di emissioni di gas climalteranti pari a 22 milioni di tonnellate di C0<sub>2<\/sub> e un sensibile risparmio in bollette per le famiglie. Senza dimenticare un altro aspetto altrettanto importante, ovvero la riduzione degli incidenti legati al consumo di gas: solo nel 2019 sono stati 270 con 35 decessi.<\/p>\n<blockquote>\n<p>Tra gli effetti del gas anche gli incidenti legati al consumo: solo nel 2019 in Italia sono stati 270 con 35 decessi<\/p>\n<\/blockquote>\n<p>Queste e altre riflessioni, supportati da dati e previsioni attendibili, emergono dal nuovo studio Elemens <a href=\"https:\/\/www.legambiente.it\/wp-content\/uploads\/sites\/24\/2021\/11\/Dal-gas-alle-rinnovabili_studio-Elemens-2022.pdf\"><strong>\u201cDal Gas alle rinnovabili. Scenari e benefici economici dalla decarbonizzazione dei sistemi di riscaldamento degli edifici\u201d<\/strong><\/a>, elaborato per Legambiente e Kyoto Club e in cui si fa un\u2019analisi sugli effetti che interventi di questo tipo potrebbero e avere su un breve periodo (al 2025) e al 2030 con interventi sul patrimonio edilizio a partire dalle case pi\u00f9 energivore (Classe G) e sostituendo i sistemi di riscaldamento domestico a gas con le pompe di calore.<\/p>\n<h2><strong>Gas, quanto ne consuma l&#8217;Italia?<\/strong><\/h2>\n<p>In Italia i consumi civili valgono 32 miliardi di metri cubi di gas ogni anno, il 43% di quelli nazionali, e contribuiscono in maniera significativa a inquinare le citt\u00e0 e a surriscaldare il Pianeta. Secondo Enea la riduzione di questi consumi nel 2020 \u00e8 stata di appena 0,3 miliardi di metri cubi di gas a fronte di 27 miliardi di euro di detrazioni fiscali. Sono 17,5 milioni, su circa 26 milioni, le abitazioni che utilizzano caldaie a gas per il riscaldamento. A fronte di questi numeri \u00e8 necessario, ora pi\u00f9 che mai con gli effetti diretti e collaterali dell&#8217;invasione russa dell&#8217;Ucraina sempre pi\u00f9 preoccupanti, rendere pi\u00f9 efficaci le politiche di incentivo per le riqualificazioni edilizie.<\/p>\n<p>\u201cL\u2019attuale crisi energetica \u2013 dichiara <strong>Edoardo Zanchini, vicepresidente di Legambiente<\/strong> \u2013 ha messo in evidenza la fragilit\u00e0 di un sistema energetico largamente basato sulle importazioni di fonti fossili e in particolare di gas. In tutto ci\u00f2 in Italia continuiamo a incentivare il gas, unico paese al mondo che regala caldaie a metano spendendo miliardi di euro ogni anno, una follia che stiamo pagando a caro prezzo.\u00a0Tutti i paesi europei e le citt\u00e0 stanno cambiando rotta, anche l\u2019Italia ha tutto l\u2019interesse a scegliere questa strada eliminando da subito il rimborso del 110% delle spese per le caldaie a gas, perch\u00e9 l\u2019obiettivo \u00e8 liberarsi dalle fossili e sostituire questi impianti con pompe di calore, come ha appena deciso di fare la Francia. E nelle nuove case, che sono gi\u00e0 a standard Nzeb, vietare l&#8217;utilizzo del gas gi\u00e0 dal prossimo anno. Possiamo raggiungere risultati ambiziosi \u2013 <strong>continua Zanchini<\/strong> &#8211; scegliendo come priorit\u00e0 gli edifici pi\u00f9 energivori e premiando chi pi\u00f9 riduce i consumi, e aiutando chi oggi sta pi\u00f9 soffrendo la crisi con interventi negli edifici di edilizia residenziale pubblica e dove vivono le famiglie in condizioni di povert\u00e0 energetica. In questo modo in pochi anni possiamo ottenere un risultato superiore alla costruzione di un nuovo gasdotto ma con benefici in termini di lavoro in Italia e riduzione delle bollette per le famiglie che possono arrivare all&#8217;80%\u201d.<\/p>\n<blockquote>\n<p>Possiamo raggiungere risultati ambiziosi\u00a0premiando chi pi\u00f9 riduce i consumi, e aiutando chi oggi sta pi\u00f9 soffrendo la crisi con interventi negli edifici di edilizia residenziale pubblica e dove vivono le famiglie in condizioni di povert\u00e0 energetica<br \/>\n<strong>&#8211; Edoardo Zanchini, vicepresidente Legambiente<\/strong><\/p>\n<\/blockquote>\n<p>&#8220;Dall&#8217;utilizzo dei combustibili fossili nel settore del riscaldamento e raffrescamento deriva il 12% delle emissioni totali di CO<sub>2<\/sub> equivalenti in UE. Inoltre, il 28% del consumo energetico annuale in Europa \u00e8 derivante dalle fonti fossili. Questo dimostra quanto sia ancora urgente agire per una decarbonizzazione degli impianti di riscaldamento, che \u00e8 l&#8217;obiettivo della campagna di Kyoto Club e Legambiente. Oggi, grazie alla presentazione del Rapporto a cura di Elemens, la riflessione \u00e8 focalizzata su questo tema. Abbiamo le tecnologie per sostituire le caldaie a gas con pompe di calore e rinnovabili: ci sono tutti i presupposti per fissare al 2025 la data di stop di installazione di sistemi di riscaldamento &#8216;fossili&#8217;&#8221;, commenta <strong>Clementina Taliento dell\u2019ufficio stampa e comunicazione di Kyoto Club.<\/strong><\/p>\n<h2><strong>Le proposte Legambiente Kyoto Club<\/strong><\/h2>\n<p>L&#8217;accelerazione del processo di decarbonizzazione deve partire dallo stop ai sussidi ambientalmente dannosi. Ma non solo. Occorre riformare l\u2019econobus, e dunque passare da incentivi legati alle tecnologie al premiare interventi integrati che riducano i fabbisogni energetici degli edifici attraverso i pi\u00f9 efficaci interventi di coibentazione, la sostituzione di impianti e reti, l&#8217;inserimento di tecnologie per l\u2019autoproduzione da fonti rinnovabili. Serve poi prevedere nell\u2019arco di tre anni la progressiva eliminazione delle agevolazioni IVA e accise su gas, senza dimenticare la progressiva decarbonizzazione dei sistemi di riscaldamento degli edifici con l\u2019eliminazione degli incentivi per l\u2019installazione delle caldaie a gas (2023 esclusione dal superbonus 110%, 2026 esclusione dalla detrazione del 50%) e il divieto di installazione nei nuovi interventi edilizi (2024) e nelle ristrutturazioni degli interi edifici (2027) nella prospettiva di elettrificazione e diffusione di pompe di calore integrate con fonti rinnovabili.<\/p>\n<h2><strong>Buone pratiche in Irlanda, Francia e Belgio<\/strong><\/h2>\n<p>Nello studio di Elemens vengono citati anche alcuni esempi di politiche adottate all\u2019estero da cui il nostro Paese potrebbe ispirarsi. Si va dall<strong>\u2019Irlanda <\/strong>dove nel febbraio del 2020 \u00e8 stato approvato un pacchetto per supportare il miglioramento delle classi energetiche degli edifici, con l\u2019obiettivo di riqualificare energeticamente 500.000 case con classe energetica pari ad almeno la classe B2. Il supporto economico consiste nell\u2019erogazione in conto capitale di un incentivo fino al 50% della spesa sostenuta per effettuare gli interventi, in particolare con attenzione alle persone che soffrono di povert\u00e0 energetica \u00e8 prevista l\u2019intera copertura dell\u2019intervento. Inoltre, gli interventi che possono avere un impatto maggiore nella riduzione del consumo energetico possono potenzialmente accedere ad un incentivo pari anche fino all\u201980% della spesa. Il piano prevede una spesa di 8 miliardi di euro al 2030.<\/p>\n<blockquote>\n<p>In\u00a0Irlanda nel 2020 \u00e8 stato approvato un pacchetto per supportare il miglioramento delle classi energetiche degli edifici, con l\u2019obiettivo di riqualificare energeticamente 500.000 case con classe energetica pari ad almeno la classe B2<\/p>\n<\/blockquote>\n<p>Altro esempio \u00e8 rappresentato dalla <strong>Francia<\/strong>, che in seguito alla crisi energetica indotta dalla situazione geopolitica, ha deciso di portare a 9.000 euro l\u2019incentivo a supporto dell\u2019installazione di pompe di calore In <strong>Belgio<\/strong>, il Climate Plan della regione delle Fiandre mira a rendere obbligatorio entro il 2023 la riqualificazione energetica degli edifici acquistati almeno fino alla classe D: questo intervento deve essere effettuato dall\u2019acquirente entro i 5 anni successivi all\u2019acquisto. Inoltre, per i nuovi edifici sar\u00e0 proibito avere un riscaldamento a gas \u2013 se non in conformazione ibrida con pompa di calore \u2013 e entro il 2026 diventer\u00e0 proibita anche la connessione alla rete del gas. Questo piano \u00e8 sostenuto da agevolazioni fiscali e sussidi nei confronti delle pompe di calore e degli impianti ibridi.<\/p>\n<p><strong>LA PRESENTAZIONE DEL RAPPORTO<\/strong><br \/>\n<iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/6cfNQak82NQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Il caso Sardegna<\/strong><\/h2>\n<p>In Italia gli occhi sono puntati sulla Sardegna che potrebbe diventare uno dei laboratori della transizione energetica. Come viene ricordato nello studio, la Sardegna \u00e8 ad oggi l\u2019unica regione italiana non ancora metanizzata tramite la rete nazionale. Questa condizione deve essere sfruttata come un\u2019opportunit\u00e0 per sperimentare gli effetti delle politiche di elettrificazione, mettendo in abbinamento l\u2019efficientamento degli edifici con una massiva penetrazione della generazione e autoproduzione da rinnovabili, sistemi di accumulo. La Sardegna pu\u00f2 puntare ad essere la prima isola green del mediterraneo, puntando su efficienza e rinnovabili, riqualificazione edilizia. L\u2019attenzione posta al tema \u00e8 confermata dagli esiti del Capacity Market, che vedono come maggiori vincitori in Sardegna gli accumuli elettrici, i quali sono in grado di fornire oggi i medesimi servizi delle centrali fossili.<\/p>\n<blockquote>\n<p>Leggi anche:<br \/>\n<a href=\"https:\/\/www.lanuovaecologia.it\/crisi-gas-fotovoltaico-agricoltura-presentazione-qualenergia-marzo-2022\/\">Ridurre la dipendenza dal gas russo<\/a><br \/>\nLa presentazione del nuovo numero di<em> QualEnergia<\/em><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/iscrizione-newsletter\/\" data-wahfont=\"27\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong>\u00a0<\/span><\/h2>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/promo\/\" data-wahfont=\"27\">REGISTRATI SUL SITO<\/a><\/strong><\/span><\/h2>\n<\/p>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riqualificando ogni anno il 3% del patrimonio edilizio e puntando sulle pompe di calore, al 2030 si potrebbe arrivare a 12 miliardi di metro cubi in meno, pari al 41% delle importazioni da Mosca. Le proposte di Legambiente e Kyoto Club nel nuovo studio di Elemens \u201cDal Gas alle rinnovabili&#8221; Ci sono strade concrete da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Riqualificando ogni anno il 3% del patrimonio edilizio e puntando sulle pompe di calore, al 2030 si potrebbe arrivare a 12 miliardi di metro cubi in meno, pari al 41% delle importazioni da Mosca. Le proposte di Legambiente e Kyoto Club nel nuovo studio di Elemens \u201cDal Gas alle rinnovabili&#8221; Ci sono strade concrete da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T08:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T11:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione\",\"datePublished\":\"2022-03-31T08:00:57+00:00\",\"dateModified\":\"2022-04-07T11:03:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/\"},\"wordCount\":1474,\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/\",\"url\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/\",\"name\":\"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\",\"datePublished\":\"2022-03-31T08:00:57+00:00\",\"dateModified\":\"2022-04-07T11:03:04+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg\",\"width\":620,\"height\":348},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\/\/forumqualenergia.it\"],\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/","og_locale":"it_IT","og_type":"article","og_title":"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023","og_description":"Riqualificando ogni anno il 3% del patrimonio edilizio e puntando sulle pompe di calore, al 2030 si potrebbe arrivare a 12 miliardi di metro cubi in meno, pari al 41% delle importazioni da Mosca. Le proposte di Legambiente e Kyoto Club nel nuovo studio di Elemens \u201cDal Gas alle rinnovabili&#8221; Ci sono strade concrete da [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2022-03-31T08:00:57+00:00","article_modified_time":"2022-04-07T11:03:04+00:00","og_image":[{"width":620,"height":348,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/"},"author":{"name":"ecfrm","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione","datePublished":"2022-03-31T08:00:57+00:00","dateModified":"2022-04-07T11:03:04+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/"},"wordCount":1474,"publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-lo-studio-import-giu-del-41-al-2030-con-piu-efficienza-nelledilizia-ed-elettrificazione\/","url":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/","name":"Gas, lo studio: import gi\u00f9 del 41% al 2030 con pi\u00f9 efficienza nell&#8217;edilizia ed elettrificazione - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg","datePublished":"2022-03-31T08:00:57+00:00","dateModified":"2022-04-07T11:03:04+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/gas-dipendenza-russia-consumi\/#primaryimage","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/03\/gas.jpg","width":620,"height":348},{"@type":"WebSite","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website","url":"https:\/\/staging.forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/staging.forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=3599"}],"version-history":[{"count":0,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/3598"}],"wp:attachment":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=3599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=3599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=3599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}