{"id":3605,"date":"2022-04-01T14:29:09","date_gmt":"2022-04-01T12:29:09","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/"},"modified":"2022-04-22T12:33:04","modified_gmt":"2022-04-22T10:33:04","slug":"transizione-energetica-accelerazione-necessaria","status":"publish","type":"post","link":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/","title":{"rendered":"Transizione energetica, accelerazione necessaria"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"420\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"impianto eolico\" loading=\"lazy\" style=\"display: block; margin: auto; margin-bottom: 5px;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg 630w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica-300x200.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg 150w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<h6><span class=\"TextRun SCXW54048547 BCX0\" lang=\"IT-IT\" xml_lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW54048547 BCX0\">La diffusione delle rinnovabili, finora rallentate da burocrazia e opposizioni locali, \u00e8 <\/span><span class=\"NormalTextRun SCXW54048547 BCX0\">obbligatoria<\/span><span class=\"NormalTextRun SCXW54048547 BCX0\">. <\/span><span class=\"NormalTextRun SCXW54048547 BCX0\">L<\/span><span class=\"NormalTextRun SCXW54048547 BCX0\">a proposta Ue di ridurre di due terzi la dipendenza dal gas russo nel 2022 impone un cambio di passo <\/span><\/span><span id=\"more-253904\"><\/span><\/h6>\n<p><span data-contrast=\"auto\"><a href=\"https:\/\/www.lanuovaecologia.it\/aprile-2022\/\" target=\"_blank\" rel=\"noopener\">Dal mensile di aprile<\/a>. L\u2019accelerazione energetica connessa alla terribile tragedia dell\u2019Ucraina e i rischi sugli approvvigionamenti del gas stanno comportando a livello europeo una spinta per una <strong>rapida accelerazione dell\u2019installazione delle rinnovabili e a un pi\u00f9 deciso impegno sul fronte dell\u2019efficienza energetica<\/strong>, in particolare nell\u2019edilizia. <\/span><span data-contrast=\"auto\">A iniziare dalla Germania che punta a 200 GW fotovoltaici nel 2030 e a 300 GW nel 2035, data entro la quale vorrebbe traguardare il risultato di 100% rinnovabili, grazie anche a una forte spinta dell\u2019eolico.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\"><strong>O dalla Danimarca che vuole coprire con le rinnovabili pi\u00f9 della met\u00e0 dei consumi totali di energia alla fine del decennio e il 100% di elettricit\u00e0 verde nel 2028<\/strong>.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">L\u2019invasione russa in Ucraina sta comportando in effetti una revisione delle politiche europee. La Ue ha proposto un piano radicale per ridurre di due terzi la dipendenza dal gas russo nel 2022. Nella stessa direzione vanno le dichiarazioni del ministro tedesco per l\u2019economia e il clima Robert Habeck: \u201cPenso decisamente che la situazione attuale aiuter\u00e0 la transizione verso le energie rinnovabili in Germania e in Europa\u201d.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">E in Italia, oltre a quelli degli ambientalisti, sono arrivati segnali molto interessanti anche da altri importanti settori.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">Le utility, infatti, hanno proposto di puntare con forza sulle rinnovabili\u202fper arrivare a\u202f60.000 MW verdi in tre anni, consentendo cos\u00ec di ridurre di quasi un quinto le importazioni di metano. Il contributo dell\u2019accelerazione delle rinnovabili da solo corrisponderebbe\u202fal taglio di met\u00e0 delle importazioni dalla Russia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">Un target molto pi\u00f9 ambizioso di quanto chiesto dalle stesse associazioni ambientaliste e che ribalta l\u2019impostazione del Piano nazionale energia e clima (Pniec) che prevedeva invece una crescita delle installazioni soprattutto nella seconda parte del decennio. Si tratterebbe di un intervento shock rispetto alla calma piatta degli ultimi anni. Siamo infatti scesi del 39% di elettricit\u00e0 verde nel 2014 al 37% del 2021.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2>Diffusione obbligata<\/h2>\n<p><span data-contrast=\"auto\">Ma \u00e8 possibile accelerare la diffusione delle rinnovabili e che contributo potrebbero dare? Terna ha ricevuto richieste di connessione alla rete elettrica per 150 GW rinnovabili, cio\u00e8 una quantit\u00e0 di gran lunga superiore rispetto ai 58 nuovi GW che il governo vorrebbe installare entro il 2030. Considerando il crollo dei prezzi del fotovoltaico e dell\u2019eolico, \u00e8 evidente che una rapida diffusione di queste tecnologie \u00e8 possibile, ma vanno superati il blocco delle autorizzazioni e le opposizioni locali.\u00a0 Sul fronte delle semplificazioni qualche timido segnale si vede e si spera che con la crisi del gas russo si proceda ad una reale accelerazione. Mentre, per quanto riguarda il consenso vanno superate le molteplici contestazioni, spesso pretestuose. In questo senso, la netta posizione di sostegno alla transizione energetica da parte di Legambiente, Wwf e Greenpeace rappresenta un forte segnale. E la diffusione delle <a href=\"https:\/\/www.lanuovaecologia.it\/comunita-energetiche-cosa-sono\/\" target=\"_blank\" rel=\"noopener\">Comunit\u00e0 energetiche<\/a> svolger\u00e0 un ruolo importante per accrescere il consenso locale.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"auto\">La diffusione su larga scala delle rinnovabili, del resto, continua inarrestabile. Ricordiamo che era green l\u201983% di tutta la potenza elettrica installata nel mondo nel 2020, una percentuale destinata ad aumentare.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2>Conflitti da prevenire<\/h2>\n<p><span data-contrast=\"auto\">Questa corsa potrebbe determinare per\u00f2 delle criticit\u00e0 sul fronte delle materie prime da utilizzare. Ma anche in questo campo ci sono segnali promettenti. Sono perseguibili infatti diversi approcci.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<blockquote>\n<p><span class=\"NormalTextRun SCXW228405786 BCX0\">Le tensioni per l\u2019accesso a petrolio e gas potrebbero essere sostituite da quelle per le terre rare. Ma <\/span><span class=\"NormalTextRun SCXW228405786 BCX0\">innovazione e riciclo <\/span><span class=\"NormalTextRun SCXW228405786 BCX0\">sono <\/span><span class=\"NormalTextRun SCXW228405786 BCX0\">promett<\/span><span class=\"NormalTextRun SCXW228405786 BCX0\">enti<\/span><\/p>\n<\/blockquote>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"auto\">Un primo percorso per contenere la pressione sugli approvvigionamenti riguarda l\u2019innovazione tecnologica. Ricordiamo che il contenuto di silicio nelle celle solari \u00e8 passato dai 16 grammi\/W nel 2004 ai 3 grammi\/W nel 2021. E si potranno aprire nuove frontiere, come con le celle solari organiche ultrasottili.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"auto\">Risulta poi molto interessante la scelta di diverse case automobilistiche di voler produrre batterie prive di cobalto e nichel, passando a soluzioni Lfp (litio, ferro, fosfato). Di grande interesse inoltre \u00e8 la ricerca per ridurre la dipendenza dalle terre rare utilizzate nei magneti permanenti usati in particolare negli aerogeneratori offshore.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><br \/>\n<\/span><span data-contrast=\"auto\">C\u2019\u00e8 poi un secondo filone che riguarda il recupero dei materiali dai prodotti a fine vita.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">Nel caso delle batterie al litio sono state avviate numerose iniziative, come la Redwood materials lanciata da Straubel, cofondatore di Tesla. E anche in Europa ci si sta attrezzando.<\/span> <span data-contrast=\"auto\"><strong>La percentuale di recupero a livello mondiale delle terre rare \u00e8 invece a livelli molto bassa, ma si ritiene di potere arrivare a recuperarne un terzo nel medio periodo<\/strong>. Alcune iniziative per il loro recupero si stanno state avviando anche fuori dalla Cina.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> \u00a0<\/span><span data-contrast=\"auto\">Abbiamo infine le nuove attivit\u00e0 di esplorazione.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-contrast=\"auto\">A settembre, ad esempio, negli Usa \u00e8 stato presentato il <\/span><i><span data-contrast=\"auto\">Reclaiming america rare earths act<\/span><\/i><span data-contrast=\"auto\">\u202fche prevede incentivi fiscali per le compagnie coinvolte nell\u2019estrazione e nel riciclo delle terre rare e di metalli nel territorio americano. La mobilitazione di investimenti pubblici e privati su vasta scala attraverso la <\/span><i><span data-contrast=\"auto\">European battery alliance<\/span><\/i><span data-contrast=\"auto\"> dovrebbero far s\u00ec che l&#8217;80\u202f% della domanda di litio sia soddisfatta da fonti europee entro il 2025. Ci sono progetti interessanti, come <\/span><i><span data-contrast=\"auto\">vulcan \u201cZero carbon Lithium\u201d<\/span><\/i><span data-contrast=\"auto\"> che prevede l\u2019estrazione di litio dal sottosuolo attraverso un ciclo geotermico a zero emissioni.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">C\u2019\u00e8 infine una riflessione pi\u00f9 di fondo, decisiva. Le possibili criticit\u00e0 sull\u2019uso delle risorse minerali e idriche impongono non solo una maggiore attenzione nel ridurre i consumi energetici, ma sollecitano anche una rivisitazione dell\u2019attuale modello economico e lanciano un messaggio a una maggiore sobriet\u00e0. Anche perch\u00e9, se finora si sono registrate forti tensioni internazionali per l\u2019accesso al petrolio e al gas, in futuro sar\u00e0 la disponibilit\u00e0 di materie prime critiche a suscitare forti appetiti e possibili scontri.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<div class=\"a-single a-117\"><a href=\"https:\/\/www.lanuovaecologia.it\/pace-rinnovabile\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Banner_Aprile_763x139.png\" \/><\/a><\/div>\n<blockquote>\n<p><strong>Leggi anche<\/strong>:<\/p>\n<p><a href=\"https:\/\/www.lanuovaecologia.it\/nuova-ecologia-aprile-2022-la-pace-e-rinnovabile\/\" target=\"_blank\" rel=\"noopener\">La pace \u00e8 rinnovabile: il numero di aprile di Nuova Ecologia<\/a><\/p>\n<\/blockquote>\n<p><strong>\u00a0<\/strong><\/p>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/iscrizione-newsletter\/\" data-wahfont=\"27\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong>\u00a0<\/span><\/h2>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/promo\/\" data-wahfont=\"27\">REGISTRATI SUL SITO<\/a><\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<\/p>\n<p align=\"right\"><strong>Gianni Silvestrini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diffusione delle rinnovabili, finora rallentate da burocrazia e opposizioni locali, \u00e8 obbligatoria. La proposta Ue di ridurre di due terzi la dipendenza dal gas russo nel 2022 impone un cambio di passo Dal mensile di aprile. L\u2019accelerazione energetica connessa alla terribile tragedia dell\u2019Ucraina e i rischi sugli approvvigionamenti del gas stanno comportando a livello [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"La diffusione delle rinnovabili, finora rallentate da burocrazia e opposizioni locali, \u00e8 obbligatoria. La proposta Ue di ridurre di due terzi la dipendenza dal gas russo nel 2022 impone un cambio di passo Dal mensile di aprile. L\u2019accelerazione energetica connessa alla terribile tragedia dell\u2019Ucraina e i rischi sugli approvvigionamenti del gas stanno comportando a livello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-01T12:29:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-22T10:33:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Transizione energetica, accelerazione necessaria\",\"datePublished\":\"2022-04-01T12:29:09+00:00\",\"dateModified\":\"2022-04-22T10:33:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/\"},\"wordCount\":952,\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/\",\"url\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/\",\"name\":\"Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\",\"datePublished\":\"2022-04-01T12:29:09+00:00\",\"dateModified\":\"2022-04-22T10:33:04+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg\",\"width\":630,\"height\":420},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#website\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\/\/forumqualenergia.it\"],\"url\":\"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/","og_locale":"it_IT","og_type":"article","og_title":"Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023","og_description":"La diffusione delle rinnovabili, finora rallentate da burocrazia e opposizioni locali, \u00e8 obbligatoria. La proposta Ue di ridurre di due terzi la dipendenza dal gas russo nel 2022 impone un cambio di passo Dal mensile di aprile. L\u2019accelerazione energetica connessa alla terribile tragedia dell\u2019Ucraina e i rischi sugli approvvigionamenti del gas stanno comportando a livello [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2022-04-01T12:29:09+00:00","article_modified_time":"2022-04-22T10:33:04+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/"},"author":{"name":"ecfrm","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Transizione energetica, accelerazione necessaria","datePublished":"2022-04-01T12:29:09+00:00","dateModified":"2022-04-22T10:33:04+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/"},"wordCount":952,"publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/transizione-energetica-accelerazione-necessaria\/","url":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/","name":"Transizione energetica, accelerazione necessaria - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg","datePublished":"2022-04-01T12:29:09+00:00","dateModified":"2022-04-22T10:33:04+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/transizione-energetica-accelerazione-rinnovabili\/#primaryimage","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/04\/Energia-Eolica.jpg","width":630,"height":420},{"@type":"WebSite","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#website","url":"https:\/\/staging.forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/staging.forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.forumqualenergia.it\/2023\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/staging.forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=3605"}],"version-history":[{"count":0,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/3606"}],"wp:attachment":[{"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=3605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=3605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=3605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}